{"id":1704,"date":"2020-04-25T06:01:52","date_gmt":"2020-04-25T06:01:52","guid":{"rendered":"https:\/\/www.indien-institut.de\/cms\/?page_id=1704"},"modified":"2020-04-25T06:04:35","modified_gmt":"2020-04-25T06:04:35","slug":"kontakt","status":"publish","type":"page","link":"https:\/\/www.indien-institut.de\/cms\/kontakt\/","title":{"rendered":"Kontakt"},"content":{"rendered":"\n\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f1702-o1\" lang=\"en-US\" dir=\"ltr\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/cms\/wp-json\/wp\/v2\/pages\/1704#wpcf7-f1702-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"1702\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"5.9.8\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f1702-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<input type=\"hidden\" name=\"_wpcf7cf_hidden_group_fields\" value=\"[]\" \/>\n<input type=\"hidden\" name=\"_wpcf7cf_hidden_groups\" value=\"[]\" \/>\n<input type=\"hidden\" name=\"_wpcf7cf_visible_groups\" value=\"[]\" \/>\n<input type=\"hidden\" name=\"_wpcf7cf_repeaters\" value=\"[]\" \/>\n<input type=\"hidden\" name=\"_wpcf7cf_steps\" value=\"{}\" \/>\n<input type=\"hidden\" name=\"_wpcf7cf_options\" value=\"{&quot;form_id&quot;:1702,&quot;conditions&quot;:[],&quot;settings&quot;:{&quot;animation&quot;:&quot;yes&quot;,&quot;animation_intime&quot;:200,&quot;animation_outtime&quot;:200,&quot;conditions_ui&quot;:&quot;normal&quot;,&quot;notice_dismissed&quot;:false,&quot;notice_dismissed_update-cf7-5.3.2&quot;:true,&quot;notice_dismissed_update-cf7-5.9.8&quot;:true}}\" \/>\n<input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/div>\n<div class=\"row\">\n\t<div class=\"col-md-4\">\n\t\t<p><label> Dein Name (erforderlich)<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span> <\/label>\n\t\t<\/p>\n\t\t<p><label> Ihre E-Mailadresse (erforderlich)<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span> <\/label>\n\t\t<\/p>\n\t\t<p><label> Gegenstand<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-subject\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-subject\" \/><\/span> <\/label>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"col-md-4\">\n\t\t<p><label> Deine Nachricht<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"your-message\"><\/textarea><\/span> <\/label>\n\t\t<\/p>\n\t\n\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Senden\" \/>\n\t\t<\/p>\n\t<\/div>\n<\/div><p style=\"display: none !important;\" class=\"akismet-fields-container\" data-prefix=\"_wpcf7_ak_\"><label>&#916;<textarea name=\"_wpcf7_ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_1\" name=\"_wpcf7_ak_js\" value=\"117\"\/><script>\ndocument.getElementById( \"ak_js_1\" ).setAttribute( \"value\", ( new Date() ).getTime() );\n<\/script>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n\n\n\n<div id=\"pl-gb1704-6a97d6d68144c\"  class=\"panel-layout\" ><div id=\"pg-gb1704-6a97d6d68144c-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-gb1704-6a97d6d68144c-0-0\"  class=\"panel-grid-cell\" ><\/div><\/div><\/div>\n\n<div\n\t\t\t\n\t\t\tclass=\"so-widget-spacer-widget so-widget-spacer-widget-base\"\n\t\t\t\n\t\t>\n<div class=\"clearfix\" style=\"height:30px\"><\/div><\/div>\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1704","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.indien-institut.de\/cms\/wp-json\/wp\/v2\/pages\/1704"}],"collection":[{"href":"https:\/\/www.indien-institut.de\/cms\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.indien-institut.de\/cms\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.indien-institut.de\/cms\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.indien-institut.de\/cms\/wp-json\/wp\/v2\/comments?post=1704"}],"version-history":[{"count":3,"href":"https:\/\/www.indien-institut.de\/cms\/wp-json\/wp\/v2\/pages\/1704\/revisions"}],"predecessor-version":[{"id":1707,"href":"https:\/\/www.indien-institut.de\/cms\/wp-json\/wp\/v2\/pages\/1704\/revisions\/1707"}],"wp:attachment":[{"href":"https:\/\/www.indien-institut.de\/cms\/wp-json\/wp\/v2\/media?parent=1704"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}